{"id":11707,"date":"2019-11-15T16:03:00","date_gmt":"2019-11-15T16:03:00","guid":{"rendered":"https:\/\/alfaloc.pt\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/"},"modified":"2025-02-20T16:41:07","modified_gmt":"2025-02-20T16:41:07","slug":"alfaloc-remporte-les-trophees-des-centres-dappels-2019","status":"publish","type":"post","link":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/","title":{"rendered":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-os-clientes-alfaloc-merecem-o-melhor-atendimento-de-sempre\">Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit !<\/h2>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"534\" src=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019-1024x534.png\" alt=\"\" class=\"wp-image-6903\" srcset=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019-1024x534.png 1024w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019-300x156.png 300w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019-768x401.png 768w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png 1204w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h6 class=\"wp-block-heading\" id=\"h-da-esquerda-para-a-direita-joana-carreira-leonor-ferraria-marta-ferreira-filipe-coelho-e-goncalo-serra\"><em>(De gauche \u00e0 droite) Joana Carreira, Leonor Ferraria, Marta Ferreira, Filipe Coelho et Gon\u00e7alo Serra.) <\/em><\/h6>\n\n<p>Et, modestie mise \u00e0 part, il est bien connu que nous nous vantons d\u2019avoir cette qualit\u00e9.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-se-forem-necessarias-provas-as-mais-valiosas-sao-as-opinioes-dos-clientes-alfaloc\"><strong>S\u2019il faut des preuves, les plus pr\u00e9cieuses sont les opinions des clients d\u2019Alfaloc.<\/strong><\/h4>\n\n<p>Mais dans le cas o\u00f9 il faudrait encore plus de preuves, nous d\u00e9cidons donc d\u2019aller au combat !<\/p>\n\n<p>C\u2019est exactement la raison pour laquelle nous avons postul\u00e9 aux Call Center Trophies 2019.<\/p>\n\n<p>Ce concours, organis\u00e9 par Call Center Magazine en partenariat avec le r\u00e9put\u00e9 IFE by Abilways, est une belle occasion de d\u00e9montrer notre excellence.<\/p>\n\n<p>En 2018, nous avons \u00e9galement particip\u00e9 \u00e0 la comp\u00e9tition, et nous avons r\u00e9ussi \u00e0 prouver la qualit\u00e9 du service en remportant les <strong>troph\u00e9es du service via les r\u00e9seaux sociaux (Facebook) et de l\u2019omnicanal.<\/strong><\/p>\n\n<p>Cette ann\u00e9e, nous avons de nouveau concouru pour les troph\u00e9es, en affrontant des g\u00e9ants du secteur, tels que <strong>Nestl\u00e9, Nescaf\u00e9 Dolce Gusto, Leroy Merlin, Santander, Meo, NOS<\/strong>, entre autres, ce qui nous rend donc encore plus fiers des r\u00e9sultats obtenus.<\/p>\n\n<p>Nous avons remport\u00e9 deux troph\u00e9es !<\/p>\n\n<p>Le premier \u00e9tait pour <strong>le service via les r\u00e9seaux sociaux<\/strong>, tandis que le second \u00e9tait pour<strong>le chat \/ Whatsapp.<\/strong><\/p>\n\n<p>Pour expliquer ces victoires, nous \u00e9num\u00e9rons ci-dessous quelques-unes des caract\u00e9ristiques les plus intrins\u00e8ques du service client Alfaloc :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Rapidit\u00e9 et efficacit\u00e9 de l\u2019intervention\u00a0;<\/strong><\/li>\n\n\n\n<li><strong>Personnalisation du service ;<\/strong><\/li>\n\n\n\n<li><strong>Sympathie et cordialit\u00e9\u00a0;<\/strong><\/li>\n\n\n\n<li><strong>Des solutions sur mesure.<\/strong><\/li>\n<\/ul>\n\n<p>Sur les r\u00e9seaux sociaux, nous renouvelons donc le label de qualit\u00e9.<\/p>\n\n<p>En ce qui concerne le service via chat\/whatsapp, nous sommes maintenant face \u00e0 une nouvelle r\u00e9alisation !<\/p>\n\n<p>Le chat sur le site web d\u2019Alfaloc est une pratique consolid\u00e9e que nous mettons en place depuis quelques ann\u00e9es, et o\u00f9 nous avons constat\u00e9, de mois en mois, une augmentation du nombre de clients qui optent pour cette forme de contact. Cela leur permet d\u2019avoir une r\u00e9ponse rapide et affirm\u00e9e en un clin d\u2019\u0153il. <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-o-whatsapp-por-sua-vez-e-uma-das-novidades-muito-recentes-da-alfaloc\">Whatsapp, quant \u00e0 lui, est l\u2019une des nouveaut\u00e9s tr\u00e8s r\u00e9centes d\u2019Alfaloc !<\/h4>\n\n<p>Cette nouveaut\u00e9, qui \u00e9tait attendue depuis un certain temps, nous semble \u00eatre devenue un grand succ\u00e8s !<\/p>\n\n<p>Afin de rendre la demande de devis, d\u2019exp\u00e9dition ou une question sur la date de r\u00e9ception de la commande de plus en plus imm\u00e9diate et pratique, Alfaloc est donc \u00e9galement disponible sur <strong>Whatsapp<\/strong>, via le num\u00e9ro <strong>917 777 100<\/strong>.<\/p>\n\n<p>Tout cela au nom de la satisfaction du client Alfaloc.<\/p>\n\n<p>Nous vous pr\u00e9sentons sur cette photo l\u2019\u00e9quipe du Service Client, principalement responsable de ces victoires :<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-premios-torfeus.jpg\" alt=\"\" class=\"wp-image-6904\" srcset=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-premios-torfeus.jpg 600w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-premios-torfeus-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n<p>Pour recevoir les prix, Filipe Coelho, directeur du service client, ainsi que Marta Ferreira, superviseure du service client, ont assist\u00e9 \u00e0 la c\u00e9r\u00e9monie.<\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"6906\" src=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2-1024x1024.png\" alt=\"\" class=\"wp-image-6906\" srcset=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2-1024x1024.png 1024w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2-300x300.png 300w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2-150x150.png 150w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2-768x768.png 768w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/notica-certificado-trofeu-2.png 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"6905\" src=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus--1024x1024.png\" alt=\"\" class=\"wp-image-6905\" srcset=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus--1024x1024.png 1024w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus--300x300.png 300w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus--150x150.png 150w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus--768x768.png 768w, https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-certificado-trofeus-.png 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n<p>Restez \u00e0 proximit\u00e9 pour plus de nouvelles.<\/p>\n\n<p>Par lui-m\u00eame, on va plus loin.<\/p>\n\n<p><strong><em>L\u2019\u00e9quipe Alfaloc<\/em><\/strong><\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p>Pour en savoir plus, rendez-vous sur :<\/p>\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/alfaloc.pt\/fr\/trophees-des-centres-dappels-2018-alfaloc-a-gagne-cette-fois-ci\/\">Alfaloc remporte les Call Center Trophies 2018<\/a><\/h4>\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/alfaloc.pt\/fr\/trophees-des-centres-dappels-2017-alfaloc-a-fait-ses-grands-debuts\/\">Alfaloc fait ses d\u00e9buts dans les Troph\u00e9es des centres d\u2019appels (2017)<\/a><\/h4>\n\n<h4 class=\"wp-block-heading\">R\u00e9f\u00e9rence aux gagnants dans les m\u00e9dias :<\/h4>\n\n<ul class=\"wp-block-list\">\n<li><strong>Magazine du centre d\u2019appels<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Annonce des laur\u00e9ats 2019 : <\/strong><a href=\"https:\/\/www.callcentermagazine.net\/contact-centers\/e-os-vencedores-do-trofeu-call-center-2019-sao\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.callcentermagazine.net\/contact-centers\/e-os-vencedores-do-trofeu-call-center-2019-sao\/<\/a><\/li>\n\n\n\n<li><strong>Laur\u00e9ats 2019, par marque :<\/strong> <a href=\"https:\/\/www.callcentermagazine.net\/trofeus-call-center\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.callcentermagazine.net\/trofeus-call-center\/<\/a><\/li>\n\n\n\n<li>Centre de contact mondial : <a href=\"https:\/\/www.callcentermagazine.net\/contact-centers\/faltam-duas-semanas-para-o-global-contact-center\/\">https:\/\/www.callcentermagazine.net\/contact-centers\/faltam-duas-semanas-para-o-global-contact-center\/<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Gestion des ressources humaines et <a href=\"https:\/\/www.human.pt\/2019\/11\/07\/edicao-21-do-global-contact-center\/\" target=\"_blank\" rel=\"noreferrer noopener\">de la https:\/\/www.human.pt\/2019\/11\/07\/edicao-21-do-global-contact-center\/<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Aper\u00e7u informatique <a href=\"https:\/\/www.itinsight.pt\/news\/eventos\/the-future-cx-is-also-human-em-destaque-no-global-contact-center-\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.itinsight.pt\/news\/eventos\/the-future-cx-is-also-human-em-destaque-no-global-contact-center-<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>La logistique et le transport <a href=\"https:\/\/www.logisticaetransporteshoje.com\/insights\/tem-um-servico-de-atendimento-ao-cliente-vencedor-candidate-se\/\">aujourd\u2019hui https:\/\/www.logisticaetransporteshoje.com\/insights\/tem-um-servico-de-atendimento-ao-cliente-vencedor-candidate-se\/<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Association Portugaise des Centres de Contact <a href=\"https:\/\/www.apcontactcenters.org\/post\/back-to-basics-the-future-cx-is-also-human\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.apcontactcenters.org\/post\/back-to-basics-the-future-cx-is-also-human<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>MSN News <a href=\"https:\/\/www.msn.com\/pt-pt\/noticias\/ultimas\/e-os-vencedores-do-trof%C3%A9u-call-center-2019-s%C3%A3o%E2%80%A6\/ar-BBWIshH\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.msn.com\/pt-pt\/noticias\/ultimas\/e-os-vencedores-do-trof%C3%A9u-call-center-2019-s%C3%A3o%E2%80%A6\/ar-BBWIshH<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Jeune <a href=\"https:\/\/www.youtube.com\/watch?v=3XDhr9wk4cg\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/watch?v=3XDhr9wk4cg<\/a> d\u2019\u00e9tude<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! (De gauche \u00e0 droite) Joana Carreira, Leonor Ferraria, Marta Ferreira, Filipe Coelho et Gon\u00e7alo Serra.) Et, modestie mise \u00e0 part, il est bien connu que nous nous vantons d\u2019avoir cette qualit\u00e9. S\u2019il faut des preuves, les plus pr\u00e9cieuses sont les opinions des clients d\u2019Alfaloc. Mais [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[239,238],"tags":[288,501,499,356,257,500,498],"class_list":["post-11707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-certifications","category-nouvelles","tag-alfaloc-fr","tag-certificat","tag-client","tag-le-sac","tag-qualite","tag-service-client-fr-2","tag-trophees-des-centres-dappels-2019"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 ! - Alfaloc<\/title>\n<meta name=\"description\" content=\"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !\" \/>\n<meta property=\"og:description\" content=\"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Alfaloc\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T16:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T16:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1204\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anitaricardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"anitaricardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/\"},\"author\":{\"name\":\"anitaricardo\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/#\\\/schema\\\/person\\\/6e8bc905f7d2b369fccf0273fc35cd80\"},\"headline\":\"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !\",\"datePublished\":\"2019-11-15T16:03:00+00:00\",\"dateModified\":\"2025-02-20T16:41:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/\"},\"wordCount\":644,\"image\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alfaloc.pt\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/noticia-trofeu-2019.png\",\"keywords\":[\"Alfaloc\",\"certificat\",\"client\",\"Le SAC\",\"qualit\u00e9\",\"Service client\",\"Troph\u00e9es des centres d\u2019appels 2019\"],\"articleSection\":[\"Certifications\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/\",\"url\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/\",\"name\":\"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 ! - Alfaloc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alfaloc.pt\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/noticia-trofeu-2019.png\",\"datePublished\":\"2019-11-15T16:03:00+00:00\",\"dateModified\":\"2025-02-20T16:41:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/#\\\/schema\\\/person\\\/6e8bc905f7d2b369fccf0273fc35cd80\"},\"description\":\"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alfaloc.pt\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/noticia-trofeu-2019.png\",\"contentUrl\":\"https:\\\/\\\/alfaloc.pt\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/noticia-trofeu-2019.png\",\"width\":1204,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/\",\"name\":\"Alfaloc\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/#\\\/schema\\\/person\\\/6e8bc905f7d2b369fccf0273fc35cd80\",\"name\":\"anitaricardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g\",\"caption\":\"anitaricardo\"},\"url\":\"https:\\\/\\\/alfaloc.pt\\\/fr\\\/author\\\/anitaricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 ! - Alfaloc","description":"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !","og_description":"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients","og_url":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/","og_site_name":"Alfaloc","article_published_time":"2019-11-15T16:03:00+00:00","article_modified_time":"2025-02-20T16:41:07+00:00","og_image":[{"width":1204,"height":628,"url":"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png","type":"image\/png"}],"author":"anitaricardo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"anitaricardo","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#article","isPartOf":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/"},"author":{"name":"anitaricardo","@id":"https:\/\/alfaloc.pt\/fr\/#\/schema\/person\/6e8bc905f7d2b369fccf0273fc35cd80"},"headline":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !","datePublished":"2019-11-15T16:03:00+00:00","dateModified":"2025-02-20T16:41:07+00:00","mainEntityOfPage":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/"},"wordCount":644,"image":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png","keywords":["Alfaloc","certificat","client","Le SAC","qualit\u00e9","Service client","Troph\u00e9es des centres d\u2019appels 2019"],"articleSection":["Certifications","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/","url":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/","name":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 ! - Alfaloc","isPartOf":{"@id":"https:\/\/alfaloc.pt\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#primaryimage"},"image":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png","datePublished":"2019-11-15T16:03:00+00:00","dateModified":"2025-02-20T16:41:07+00:00","author":{"@id":"https:\/\/alfaloc.pt\/fr\/#\/schema\/person\/6e8bc905f7d2b369fccf0273fc35cd80"},"description":"Les clients d\u2019Alfaloc m\u00e9ritent le meilleur service qui soit ! Si des preuves sont n\u00e9cessaires, les plus pr\u00e9cieuses sont les opinions de nos clients","breadcrumb":{"@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#primaryimage","url":"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png","contentUrl":"https:\/\/alfaloc.pt\/wp-content\/uploads\/2024\/08\/noticia-trofeu-2019.png","width":1204,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/alfaloc.pt\/fr\/alfaloc-remporte-les-trophees-des-centres-dappels-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/alfaloc.pt\/fr\/"},{"@type":"ListItem","position":2,"name":"Alfaloc remporte les Troph\u00e9es des centres d\u2019appels 2019 !"}]},{"@type":"WebSite","@id":"https:\/\/alfaloc.pt\/fr\/#website","url":"https:\/\/alfaloc.pt\/fr\/","name":"Alfaloc","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alfaloc.pt\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/alfaloc.pt\/fr\/#\/schema\/person\/6e8bc905f7d2b369fccf0273fc35cd80","name":"anitaricardo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e5ec89c52b1d32d7ab680e5de52c29e4c855c3ecd63735926f623145fb3517a?s=96&d=mm&r=g","caption":"anitaricardo"},"url":"https:\/\/alfaloc.pt\/fr\/author\/anitaricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/posts\/11707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/comments?post=11707"}],"version-history":[{"count":1,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/posts\/11707\/revisions"}],"predecessor-version":[{"id":11708,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/posts\/11707\/revisions\/11708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/media\/10139"}],"wp:attachment":[{"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/media?parent=11707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/categories?post=11707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alfaloc.pt\/fr\/wp-json\/wp\/v2\/tags?post=11707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}